{"id":1181,"date":"2017-06-13T13:16:12","date_gmt":"2017-06-13T11:16:12","guid":{"rendered":"https:\/\/www.prochaska.eu\/?p=1181"},"modified":"2017-06-13T13:16:12","modified_gmt":"2017-06-13T11:16:12","slug":"eine-starke-partnerschaft-fuer-wiens-gruene-wiesen","status":"publish","type":"post","link":"https:\/\/prochaska.eu\/en\/eine-starke-partnerschaft-fuer-wiens-gruene-wiesen\/","title":{"rendered":"Eine starke Partnerschaft f\u00fcr Wiens gr\u00fcne Wiesen"},"content":{"rendered":"<p>Die Stadt Wien ist weltweit bekannt f\u00fcr ihre Vielzahl an frei zug\u00e4nglichen und top-gepflegten Parks und Gr\u00fcnfl\u00e4chen. Zur Pflege dieser Wiesen braucht es einen starken und verl\u00e4sslichen Partner. Seit <strong>rund 40 Jahren<\/strong> sind deshalb TORO Rasenm\u00e4her und M\u00e4hmaschinen in <strong>950 Parks und Gr\u00fcnanlagen<\/strong> f\u00fcr die Wiener Stadtg\u00e4rten (MA 42) und weitere 16 Magistratsabteilungen im Einsatz. Vom gr\u00f6\u00dften TORO Sichelm\u00e4her mit f\u00fcnf Metern Schnittbreite im Prater bis hin zu besonders leistungsf\u00e4higen Benzinrasenm\u00e4hern zum M\u00e4hen der kleineren Fl\u00e4chen beispielsweise entlang der Ringstra\u00dfe sind TORO Maschinen zwischen April und Oktober t\u00e4glich in Betrieb. Und etliche dieser Ger\u00e4te liefern bei entsprechender Pflege und professionellem Service bis zu 15 Jahre und l\u00e4nger die volle Leistung.<\/p>\n<p>TORO Maschinen sind bekannt f\u00fcr ihre Benutzerfreundlichkeit, innovative Technik und hochwertige Verarbeitung \u2013 die besten Argumente, wenn Profis Maschinen kaufen. Eigene TORO Servicemechaniker stellen die professionelle Wartung der Ger\u00e4te und die Versorgung mit den wichtigsten Ersatzteilen meist binnen 48 Stunden sicher.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Die Stadt Wien ist weltweit bekannt f\u00fcr ihre Vielzahl an frei zug\u00e4nglichen und top-gepflegten Parks und Gr\u00fcnfl\u00e4chen. Zur Pflege dieser Wiesen braucht es einen starken und verl\u00e4sslichen Partner. Seit rund 40 Jahren sind deshalb TORO Rasenm\u00e4her und M\u00e4hmaschinen in 950 Parks und Gr\u00fcnanlagen f\u00fcr die Wiener Stadtg\u00e4rten (MA 42) und weitere 16 Magistratsabteilungen im Einsatz. [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":1369,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1024],"tags":[],"class_list":["post-1181","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-toro-in-action"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Eine starke Partnerschaft f\u00fcr Wiens gr\u00fcne Wiesen - Prochaska<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/prochaska.eu\/en\/eine-starke-partnerschaft-fuer-wiens-gruene-wiesen\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Eine starke Partnerschaft f\u00fcr Wiens gr\u00fcne Wiesen - Prochaska\" \/>\n<meta property=\"og:description\" content=\"Die Stadt Wien ist weltweit bekannt f\u00fcr ihre Vielzahl an frei zug\u00e4nglichen und top-gepflegten Parks und Gr\u00fcnfl\u00e4chen. Zur Pflege dieser Wiesen braucht es einen starken und verl\u00e4sslichen Partner. Seit rund 40 Jahren sind deshalb TORO Rasenm\u00e4her und M\u00e4hmaschinen in 950 Parks und Gr\u00fcnanlagen f\u00fcr die Wiener Stadtg\u00e4rten (MA 42) und weitere 16 Magistratsabteilungen im Einsatz. [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/prochaska.eu\/en\/eine-starke-partnerschaft-fuer-wiens-gruene-wiesen\/\" \/>\n<meta property=\"og:site_name\" content=\"Prochaska\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/prochaska.eu\/\" \/>\n<meta property=\"article:published_time\" content=\"2017-06-13T11:16:12+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/prochaska.eu\/wp-content\/uploads\/2017\/06\/Prater.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2160\" \/>\n\t<meta property=\"og:image:height\" content=\"1216\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Marketing\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Marketing\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/prochaska.eu\\\/en\\\/eine-starke-partnerschaft-fuer-wiens-gruene-wiesen\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/prochaska.eu\\\/en\\\/eine-starke-partnerschaft-fuer-wiens-gruene-wiesen\\\/\"},\"author\":{\"name\":\"Marketing\",\"@id\":\"https:\\\/\\\/prochaska.eu\\\/en\\\/#\\\/schema\\\/person\\\/f8db8ee1a0c8154de4226e7eca116a21\"},\"headline\":\"Eine starke Partnerschaft f\u00fcr Wiens gr\u00fcne Wiesen\",\"datePublished\":\"2017-06-13T11:16:12+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/prochaska.eu\\\/en\\\/eine-starke-partnerschaft-fuer-wiens-gruene-wiesen\\\/\"},\"wordCount\":176,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/prochaska.eu\\\/en\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/prochaska.eu\\\/en\\\/eine-starke-partnerschaft-fuer-wiens-gruene-wiesen\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/prochaska.eu\\\/wp-content\\\/uploads\\\/2017\\\/06\\\/Prater.jpg\",\"articleSection\":[\"Toro in Action\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/prochaska.eu\\\/en\\\/eine-starke-partnerschaft-fuer-wiens-gruene-wiesen\\\/\",\"url\":\"https:\\\/\\\/prochaska.eu\\\/en\\\/eine-starke-partnerschaft-fuer-wiens-gruene-wiesen\\\/\",\"name\":\"Eine starke Partnerschaft f\u00fcr Wiens gr\u00fcne Wiesen - Prochaska\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/prochaska.eu\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/prochaska.eu\\\/en\\\/eine-starke-partnerschaft-fuer-wiens-gruene-wiesen\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/prochaska.eu\\\/en\\\/eine-starke-partnerschaft-fuer-wiens-gruene-wiesen\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/prochaska.eu\\\/wp-content\\\/uploads\\\/2017\\\/06\\\/Prater.jpg\",\"datePublished\":\"2017-06-13T11:16:12+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/prochaska.eu\\\/en\\\/eine-starke-partnerschaft-fuer-wiens-gruene-wiesen\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/prochaska.eu\\\/en\\\/eine-starke-partnerschaft-fuer-wiens-gruene-wiesen\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/prochaska.eu\\\/en\\\/eine-starke-partnerschaft-fuer-wiens-gruene-wiesen\\\/#primaryimage\",\"url\":\"https:\\\/\\\/prochaska.eu\\\/wp-content\\\/uploads\\\/2017\\\/06\\\/Prater.jpg\",\"contentUrl\":\"https:\\\/\\\/prochaska.eu\\\/wp-content\\\/uploads\\\/2017\\\/06\\\/Prater.jpg\",\"width\":2160,\"height\":1216,\"caption\":\"Toro Wien Prater\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/prochaska.eu\\\/en\\\/eine-starke-partnerschaft-fuer-wiens-gruene-wiesen\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/prochaska.eu\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Eine starke Partnerschaft f\u00fcr Wiens gr\u00fcne Wiesen\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/prochaska.eu\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/prochaska.eu\\\/en\\\/\",\"name\":\"Prochaska\",\"description\":\"Spezialist f\u00fcr Pflege von Gr\u00fcnfl\u00e4chen\",\"publisher\":{\"@id\":\"https:\\\/\\\/prochaska.eu\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/prochaska.eu\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/prochaska.eu\\\/en\\\/#organization\",\"name\":\"Prochaska\",\"url\":\"https:\\\/\\\/prochaska.eu\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/prochaska.eu\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/prochaska.eu\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/Prochaska_Logo_Black-1.png\",\"contentUrl\":\"https:\\\/\\\/prochaska.eu\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/Prochaska_Logo_Black-1.png\",\"width\":796,\"height\":236,\"caption\":\"Prochaska\"},\"image\":{\"@id\":\"https:\\\/\\\/prochaska.eu\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/prochaska.eu\\\/\",\"https:\\\/\\\/www.instagram.com\\\/prochaska.eu\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/prochaska-handels-gmbh\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/prochaska.eu\\\/en\\\/#\\\/schema\\\/person\\\/f8db8ee1a0c8154de4226e7eca116a21\",\"name\":\"Marketing\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f444570ec15afe2872a9cd3679ab47c5a9195f1dec2e6bd4ede295b2bc9c0663?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f444570ec15afe2872a9cd3679ab47c5a9195f1dec2e6bd4ede295b2bc9c0663?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f444570ec15afe2872a9cd3679ab47c5a9195f1dec2e6bd4ede295b2bc9c0663?s=96&d=mm&r=g\",\"caption\":\"Marketing\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Eine starke Partnerschaft f\u00fcr Wiens gr\u00fcne Wiesen - Prochaska","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/prochaska.eu\/en\/eine-starke-partnerschaft-fuer-wiens-gruene-wiesen\/","og_locale":"en_US","og_type":"article","og_title":"Eine starke Partnerschaft f\u00fcr Wiens gr\u00fcne Wiesen - Prochaska","og_description":"Die Stadt Wien ist weltweit bekannt f\u00fcr ihre Vielzahl an frei zug\u00e4nglichen und top-gepflegten Parks und Gr\u00fcnfl\u00e4chen. Zur Pflege dieser Wiesen braucht es einen starken und verl\u00e4sslichen Partner. Seit rund 40 Jahren sind deshalb TORO Rasenm\u00e4her und M\u00e4hmaschinen in 950 Parks und Gr\u00fcnanlagen f\u00fcr die Wiener Stadtg\u00e4rten (MA 42) und weitere 16 Magistratsabteilungen im Einsatz. [&hellip;]","og_url":"https:\/\/prochaska.eu\/en\/eine-starke-partnerschaft-fuer-wiens-gruene-wiesen\/","og_site_name":"Prochaska","article_publisher":"https:\/\/www.facebook.com\/prochaska.eu\/","article_published_time":"2017-06-13T11:16:12+00:00","og_image":[{"width":2160,"height":1216,"url":"https:\/\/prochaska.eu\/wp-content\/uploads\/2017\/06\/Prater.jpg","type":"image\/jpeg"}],"author":"Marketing","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Marketing","Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/prochaska.eu\/en\/eine-starke-partnerschaft-fuer-wiens-gruene-wiesen\/#article","isPartOf":{"@id":"https:\/\/prochaska.eu\/en\/eine-starke-partnerschaft-fuer-wiens-gruene-wiesen\/"},"author":{"name":"Marketing","@id":"https:\/\/prochaska.eu\/en\/#\/schema\/person\/f8db8ee1a0c8154de4226e7eca116a21"},"headline":"Eine starke Partnerschaft f\u00fcr Wiens gr\u00fcne Wiesen","datePublished":"2017-06-13T11:16:12+00:00","mainEntityOfPage":{"@id":"https:\/\/prochaska.eu\/en\/eine-starke-partnerschaft-fuer-wiens-gruene-wiesen\/"},"wordCount":176,"commentCount":0,"publisher":{"@id":"https:\/\/prochaska.eu\/en\/#organization"},"image":{"@id":"https:\/\/prochaska.eu\/en\/eine-starke-partnerschaft-fuer-wiens-gruene-wiesen\/#primaryimage"},"thumbnailUrl":"https:\/\/prochaska.eu\/wp-content\/uploads\/2017\/06\/Prater.jpg","articleSection":["Toro in Action"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/prochaska.eu\/en\/eine-starke-partnerschaft-fuer-wiens-gruene-wiesen\/","url":"https:\/\/prochaska.eu\/en\/eine-starke-partnerschaft-fuer-wiens-gruene-wiesen\/","name":"Eine starke Partnerschaft f\u00fcr Wiens gr\u00fcne Wiesen - Prochaska","isPartOf":{"@id":"https:\/\/prochaska.eu\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/prochaska.eu\/en\/eine-starke-partnerschaft-fuer-wiens-gruene-wiesen\/#primaryimage"},"image":{"@id":"https:\/\/prochaska.eu\/en\/eine-starke-partnerschaft-fuer-wiens-gruene-wiesen\/#primaryimage"},"thumbnailUrl":"https:\/\/prochaska.eu\/wp-content\/uploads\/2017\/06\/Prater.jpg","datePublished":"2017-06-13T11:16:12+00:00","breadcrumb":{"@id":"https:\/\/prochaska.eu\/en\/eine-starke-partnerschaft-fuer-wiens-gruene-wiesen\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/prochaska.eu\/en\/eine-starke-partnerschaft-fuer-wiens-gruene-wiesen\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/prochaska.eu\/en\/eine-starke-partnerschaft-fuer-wiens-gruene-wiesen\/#primaryimage","url":"https:\/\/prochaska.eu\/wp-content\/uploads\/2017\/06\/Prater.jpg","contentUrl":"https:\/\/prochaska.eu\/wp-content\/uploads\/2017\/06\/Prater.jpg","width":2160,"height":1216,"caption":"Toro Wien Prater"},{"@type":"BreadcrumbList","@id":"https:\/\/prochaska.eu\/en\/eine-starke-partnerschaft-fuer-wiens-gruene-wiesen\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/prochaska.eu\/en\/"},{"@type":"ListItem","position":2,"name":"Eine starke Partnerschaft f\u00fcr Wiens gr\u00fcne Wiesen"}]},{"@type":"WebSite","@id":"https:\/\/prochaska.eu\/en\/#website","url":"https:\/\/prochaska.eu\/en\/","name":"Prochaska","description":"Spezialist f\u00fcr Pflege von Gr\u00fcnfl\u00e4chen","publisher":{"@id":"https:\/\/prochaska.eu\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/prochaska.eu\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/prochaska.eu\/en\/#organization","name":"Prochaska","url":"https:\/\/prochaska.eu\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/prochaska.eu\/en\/#\/schema\/logo\/image\/","url":"https:\/\/prochaska.eu\/wp-content\/uploads\/2024\/04\/Prochaska_Logo_Black-1.png","contentUrl":"https:\/\/prochaska.eu\/wp-content\/uploads\/2024\/04\/Prochaska_Logo_Black-1.png","width":796,"height":236,"caption":"Prochaska"},"image":{"@id":"https:\/\/prochaska.eu\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/prochaska.eu\/","https:\/\/www.instagram.com\/prochaska.eu\/","https:\/\/www.linkedin.com\/company\/prochaska-handels-gmbh"]},{"@type":"Person","@id":"https:\/\/prochaska.eu\/en\/#\/schema\/person\/f8db8ee1a0c8154de4226e7eca116a21","name":"Marketing","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/f444570ec15afe2872a9cd3679ab47c5a9195f1dec2e6bd4ede295b2bc9c0663?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/f444570ec15afe2872a9cd3679ab47c5a9195f1dec2e6bd4ede295b2bc9c0663?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f444570ec15afe2872a9cd3679ab47c5a9195f1dec2e6bd4ede295b2bc9c0663?s=96&d=mm&r=g","caption":"Marketing"}}]}},"_links":{"self":[{"href":"https:\/\/prochaska.eu\/en\/wp-json\/wp\/v2\/posts\/1181","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/prochaska.eu\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/prochaska.eu\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/prochaska.eu\/en\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/prochaska.eu\/en\/wp-json\/wp\/v2\/comments?post=1181"}],"version-history":[{"count":0,"href":"https:\/\/prochaska.eu\/en\/wp-json\/wp\/v2\/posts\/1181\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/prochaska.eu\/en\/wp-json\/wp\/v2\/media\/1369"}],"wp:attachment":[{"href":"https:\/\/prochaska.eu\/en\/wp-json\/wp\/v2\/media?parent=1181"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/prochaska.eu\/en\/wp-json\/wp\/v2\/categories?post=1181"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/prochaska.eu\/en\/wp-json\/wp\/v2\/tags?post=1181"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}