{"id":7064,"date":"2019-11-18T11:56:34","date_gmt":"2019-11-18T10:56:34","guid":{"rendered":"https:\/\/www.prochaska.eu\/?p=7064"},"modified":"2019-11-18T11:56:34","modified_gmt":"2019-11-18T10:56:34","slug":"rasenmaeher-einwintern-2","status":"publish","type":"post","link":"https:\/\/prochaska.eu\/en\/rasenmaeher-einwintern-2\/","title":{"rendered":"KIOTI Europe Service School 2019"},"content":{"rendered":"<p>Wien im November 2019. Die <a class=\"profileLink\" href=\"https:\/\/www.prochaska.eu\/kioti\/\" data-hovercard=\"\/ajax\/hovercard\/page.php?id=295699560235&amp;extragetparams=%7B%22__tn__%22%3A%22%2CdK-R-R%22%2C%22eid%22%3A%22ARCaUSFq9sJ_yCtO0Ud7dRxrmp3SBxsrWWByY9RYT_J0iiDf2gWu_26-UCWdOqjg11hJ1GCjHKpmO1mv%22%2C%22fref%22%3A%22mentions%22%7D\" data-hovercard-prefer-more-content-show=\"1\">KIOTI<\/a> Europe Service School 2019 fand heuer in Wien bei der Prochaska Handels GmbH statt: Unter der Leitung von Ws.Choi und K.J. Kim wurden rund 40 Teilnehmer aus ganz Europa auf den neuesten Stand der Technik gebracht!<\/p>\n<h2>Weiterbildung und ein bisschen Wien<\/h2>\n<p>Im Rahmen des Workshops von KIOTI gab es nicht nur theoretische Vortr\u00e4ge und Diskussionsrunden, sondern auch praktische Einheiten direkt am Traktor. Abgerundet wurde das Programm durch eine F\u00fchrung durch Wien und kulinarische Leckerbissen.<\/p>\n<h2 style=\"text-align: left;\">KIOTI ist Top-Traktoren-Marke<\/h2>\n<p>Die Marke <a href=\"https:\/\/www.prochaska.eu\/kioti\/\">KIOTI<\/a> ist der gr\u00f6\u00dfte koreanische Traktorenhersteller und vertreibt die Traktoren mit Top-Qualit\u00e4t weltweit.\u00a0 KIOTI konnte in \u00d6sterreich 2018 bereits den vierth\u00f6chsten Marktanteil im Bereich Kommunaltraktoren verzeichnen. Das Unternehmen investiert in die Entwicklung von Fertigungsanlagen.<\/p>\n<p>Dr. Andreas Heger, Gesch\u00e4ftsf\u00fchrer von Prochaska: &#8220;Wir vertreiben KIOTI seit nunmehr 14 Jahre in ganz \u00d6sterreich und verf\u00fcgen \u00fcber eine eigene Werkstatt in Wien mit laufend geschulten KIOTI-Mechanikern. Seit Anfang 2019 k\u00fcmmert sich KIOTI um den deutschen Markt selbst, nachdem hier bis dato Distributoren t\u00e4tig waren. Es sind davon extrem positive Effekte auch f\u00fcr den \u00f6sterreichischen Markt, vor allem bei der Ersatzteilversorgung, zu erwarten.&#8221;<\/p>\n<p>Besuchen Sie uns in der Pilzgasse 31, 1210 Wien oder kontaktieren Sie uns unter sales@prochaska.eu oder +43 278 51 00.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Wien im November 2019. Die KIOTI Europe Service School 2019 fand heuer in Wien bei der Prochaska Handels GmbH statt: Unter der Leitung von Ws.Choi und K.J. Kim wurden rund 40 Teilnehmer aus ganz Europa auf den neuesten Stand der Technik gebracht! Weiterbildung und ein bisschen Wien Im Rahmen des Workshops von KIOTI gab es [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":7070,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1023],"tags":[],"class_list":["post-7064","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-events"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>TORO Beregnungssysteme - Einwinterung<\/title>\n<meta name=\"description\" content=\"Bevor es so richtig frostig wird muss der Garten winterfit gemacht werden - dazu geh\u00f6rt auch die Einwinterung von Beregnungssystemen.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/prochaska.eu\/en\/rasenmaeher-einwintern-2\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Rasenm\u00e4her I Reinigung, Wartung &amp; Einwinterung\" \/>\n<meta property=\"og:description\" content=\"Bevor der erste Schnee f\u00e4llt sollte der Rasen noch ein letztes Mal gem\u00e4ht werden, denn wenn die Halme zu lang sind, knicken Sie leicht und nehmen Schaden. Sobald dies erledigt ist, geht es darum den Rasenm\u00e4her einzuwintern. Hierf\u00fcr gibt es einige Regeln, die zu beachten sind, sodass man im Fr\u00fchjahr wieder ohne Probleme in die Gartensaison zu starten kann.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/prochaska.eu\/en\/rasenmaeher-einwintern-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Prochaska\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/prochaska.eu\/\" \/>\n<meta property=\"article:published_time\" content=\"2019-11-18T10:56:34+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/prochaska.eu\/wp-content\/uploads\/2019\/11\/toro-rasenmaeher-einwintern-blog-facebook.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Marketing\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Rasenm\u00e4her I Reinigung, Wartung &amp; Einwinterung\" \/>\n<meta name=\"twitter:description\" content=\"Bevor der erste Schnee f\u00e4llt sollte der Rasen noch ein letztes Mal gem\u00e4ht werden, danach geht es darum den Rasenm\u00e4her einzuwintern.\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/prochaska.eu\/wp-content\/uploads\/2019\/11\/toro-rasenmaeher-einwintern-blog-twitter.jpg.jpg\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Marketing\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/prochaska.eu\\\/en\\\/rasenmaeher-einwintern-2\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/prochaska.eu\\\/en\\\/rasenmaeher-einwintern-2\\\/\"},\"author\":{\"name\":\"Marketing\",\"@id\":\"https:\\\/\\\/prochaska.eu\\\/en\\\/#\\\/schema\\\/person\\\/f8db8ee1a0c8154de4226e7eca116a21\"},\"headline\":\"KIOTI Europe Service School 2019\",\"datePublished\":\"2019-11-18T10:56:34+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/prochaska.eu\\\/en\\\/rasenmaeher-einwintern-2\\\/\"},\"wordCount\":211,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/prochaska.eu\\\/en\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/prochaska.eu\\\/en\\\/rasenmaeher-einwintern-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/prochaska.eu\\\/wp-content\\\/uploads\\\/2019\\\/11\\\/kioti-serviceschool-europe-blog4.jpg\",\"articleSection\":[\"Events\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/prochaska.eu\\\/en\\\/rasenmaeher-einwintern-2\\\/\",\"url\":\"https:\\\/\\\/prochaska.eu\\\/en\\\/rasenmaeher-einwintern-2\\\/\",\"name\":\"TORO Beregnungssysteme - Einwinterung\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/prochaska.eu\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/prochaska.eu\\\/en\\\/rasenmaeher-einwintern-2\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/prochaska.eu\\\/en\\\/rasenmaeher-einwintern-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/prochaska.eu\\\/wp-content\\\/uploads\\\/2019\\\/11\\\/kioti-serviceschool-europe-blog4.jpg\",\"datePublished\":\"2019-11-18T10:56:34+00:00\",\"description\":\"Bevor es so richtig frostig wird muss der Garten winterfit gemacht werden - dazu geh\u00f6rt auch die Einwinterung von Beregnungssystemen.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/prochaska.eu\\\/en\\\/rasenmaeher-einwintern-2\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/prochaska.eu\\\/en\\\/rasenmaeher-einwintern-2\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/prochaska.eu\\\/en\\\/rasenmaeher-einwintern-2\\\/#primaryimage\",\"url\":\"https:\\\/\\\/prochaska.eu\\\/wp-content\\\/uploads\\\/2019\\\/11\\\/kioti-serviceschool-europe-blog4.jpg\",\"contentUrl\":\"https:\\\/\\\/prochaska.eu\\\/wp-content\\\/uploads\\\/2019\\\/11\\\/kioti-serviceschool-europe-blog4.jpg\",\"width\":2160,\"height\":1216},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/prochaska.eu\\\/en\\\/rasenmaeher-einwintern-2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/prochaska.eu\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"KIOTI Europe Service School 2019\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/prochaska.eu\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/prochaska.eu\\\/en\\\/\",\"name\":\"Prochaska\",\"description\":\"Spezialist f\u00fcr Pflege von Gr\u00fcnfl\u00e4chen\",\"publisher\":{\"@id\":\"https:\\\/\\\/prochaska.eu\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/prochaska.eu\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/prochaska.eu\\\/en\\\/#organization\",\"name\":\"Prochaska\",\"url\":\"https:\\\/\\\/prochaska.eu\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/prochaska.eu\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/prochaska.eu\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/Prochaska_Logo_Black-1.png\",\"contentUrl\":\"https:\\\/\\\/prochaska.eu\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/Prochaska_Logo_Black-1.png\",\"width\":796,\"height\":236,\"caption\":\"Prochaska\"},\"image\":{\"@id\":\"https:\\\/\\\/prochaska.eu\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/prochaska.eu\\\/\",\"https:\\\/\\\/www.instagram.com\\\/prochaska.eu\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/prochaska-handels-gmbh\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/prochaska.eu\\\/en\\\/#\\\/schema\\\/person\\\/f8db8ee1a0c8154de4226e7eca116a21\",\"name\":\"Marketing\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f444570ec15afe2872a9cd3679ab47c5a9195f1dec2e6bd4ede295b2bc9c0663?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f444570ec15afe2872a9cd3679ab47c5a9195f1dec2e6bd4ede295b2bc9c0663?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f444570ec15afe2872a9cd3679ab47c5a9195f1dec2e6bd4ede295b2bc9c0663?s=96&d=mm&r=g\",\"caption\":\"Marketing\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"TORO Beregnungssysteme - Einwinterung","description":"Bevor es so richtig frostig wird muss der Garten winterfit gemacht werden - dazu geh\u00f6rt auch die Einwinterung von Beregnungssystemen.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/prochaska.eu\/en\/rasenmaeher-einwintern-2\/","og_locale":"en_US","og_type":"article","og_title":"Rasenm\u00e4her I Reinigung, Wartung & Einwinterung","og_description":"Bevor der erste Schnee f\u00e4llt sollte der Rasen noch ein letztes Mal gem\u00e4ht werden, denn wenn die Halme zu lang sind, knicken Sie leicht und nehmen Schaden. Sobald dies erledigt ist, geht es darum den Rasenm\u00e4her einzuwintern. Hierf\u00fcr gibt es einige Regeln, die zu beachten sind, sodass man im Fr\u00fchjahr wieder ohne Probleme in die Gartensaison zu starten kann.","og_url":"https:\/\/prochaska.eu\/en\/rasenmaeher-einwintern-2\/","og_site_name":"Prochaska","article_publisher":"https:\/\/www.facebook.com\/prochaska.eu\/","article_published_time":"2019-11-18T10:56:34+00:00","og_image":[{"width":1200,"height":630,"url":"https:\/\/prochaska.eu\/wp-content\/uploads\/2019\/11\/toro-rasenmaeher-einwintern-blog-facebook.jpg","type":"image\/jpeg"}],"author":"Marketing","twitter_card":"summary_large_image","twitter_title":"Rasenm\u00e4her I Reinigung, Wartung & Einwinterung","twitter_description":"Bevor der erste Schnee f\u00e4llt sollte der Rasen noch ein letztes Mal gem\u00e4ht werden, danach geht es darum den Rasenm\u00e4her einzuwintern.","twitter_image":"https:\/\/prochaska.eu\/wp-content\/uploads\/2019\/11\/toro-rasenmaeher-einwintern-blog-twitter.jpg.jpg","twitter_misc":{"Written by":"Marketing","Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/prochaska.eu\/en\/rasenmaeher-einwintern-2\/#article","isPartOf":{"@id":"https:\/\/prochaska.eu\/en\/rasenmaeher-einwintern-2\/"},"author":{"name":"Marketing","@id":"https:\/\/prochaska.eu\/en\/#\/schema\/person\/f8db8ee1a0c8154de4226e7eca116a21"},"headline":"KIOTI Europe Service School 2019","datePublished":"2019-11-18T10:56:34+00:00","mainEntityOfPage":{"@id":"https:\/\/prochaska.eu\/en\/rasenmaeher-einwintern-2\/"},"wordCount":211,"commentCount":0,"publisher":{"@id":"https:\/\/prochaska.eu\/en\/#organization"},"image":{"@id":"https:\/\/prochaska.eu\/en\/rasenmaeher-einwintern-2\/#primaryimage"},"thumbnailUrl":"https:\/\/prochaska.eu\/wp-content\/uploads\/2019\/11\/kioti-serviceschool-europe-blog4.jpg","articleSection":["Events"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/prochaska.eu\/en\/rasenmaeher-einwintern-2\/","url":"https:\/\/prochaska.eu\/en\/rasenmaeher-einwintern-2\/","name":"TORO Beregnungssysteme - Einwinterung","isPartOf":{"@id":"https:\/\/prochaska.eu\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/prochaska.eu\/en\/rasenmaeher-einwintern-2\/#primaryimage"},"image":{"@id":"https:\/\/prochaska.eu\/en\/rasenmaeher-einwintern-2\/#primaryimage"},"thumbnailUrl":"https:\/\/prochaska.eu\/wp-content\/uploads\/2019\/11\/kioti-serviceschool-europe-blog4.jpg","datePublished":"2019-11-18T10:56:34+00:00","description":"Bevor es so richtig frostig wird muss der Garten winterfit gemacht werden - dazu geh\u00f6rt auch die Einwinterung von Beregnungssystemen.","breadcrumb":{"@id":"https:\/\/prochaska.eu\/en\/rasenmaeher-einwintern-2\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/prochaska.eu\/en\/rasenmaeher-einwintern-2\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/prochaska.eu\/en\/rasenmaeher-einwintern-2\/#primaryimage","url":"https:\/\/prochaska.eu\/wp-content\/uploads\/2019\/11\/kioti-serviceschool-europe-blog4.jpg","contentUrl":"https:\/\/prochaska.eu\/wp-content\/uploads\/2019\/11\/kioti-serviceschool-europe-blog4.jpg","width":2160,"height":1216},{"@type":"BreadcrumbList","@id":"https:\/\/prochaska.eu\/en\/rasenmaeher-einwintern-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/prochaska.eu\/en\/"},{"@type":"ListItem","position":2,"name":"KIOTI Europe Service School 2019"}]},{"@type":"WebSite","@id":"https:\/\/prochaska.eu\/en\/#website","url":"https:\/\/prochaska.eu\/en\/","name":"Prochaska","description":"Spezialist f\u00fcr Pflege von Gr\u00fcnfl\u00e4chen","publisher":{"@id":"https:\/\/prochaska.eu\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/prochaska.eu\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/prochaska.eu\/en\/#organization","name":"Prochaska","url":"https:\/\/prochaska.eu\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/prochaska.eu\/en\/#\/schema\/logo\/image\/","url":"https:\/\/prochaska.eu\/wp-content\/uploads\/2024\/04\/Prochaska_Logo_Black-1.png","contentUrl":"https:\/\/prochaska.eu\/wp-content\/uploads\/2024\/04\/Prochaska_Logo_Black-1.png","width":796,"height":236,"caption":"Prochaska"},"image":{"@id":"https:\/\/prochaska.eu\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/prochaska.eu\/","https:\/\/www.instagram.com\/prochaska.eu\/","https:\/\/www.linkedin.com\/company\/prochaska-handels-gmbh"]},{"@type":"Person","@id":"https:\/\/prochaska.eu\/en\/#\/schema\/person\/f8db8ee1a0c8154de4226e7eca116a21","name":"Marketing","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/f444570ec15afe2872a9cd3679ab47c5a9195f1dec2e6bd4ede295b2bc9c0663?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/f444570ec15afe2872a9cd3679ab47c5a9195f1dec2e6bd4ede295b2bc9c0663?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f444570ec15afe2872a9cd3679ab47c5a9195f1dec2e6bd4ede295b2bc9c0663?s=96&d=mm&r=g","caption":"Marketing"}}]}},"_links":{"self":[{"href":"https:\/\/prochaska.eu\/en\/wp-json\/wp\/v2\/posts\/7064","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/prochaska.eu\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/prochaska.eu\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/prochaska.eu\/en\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/prochaska.eu\/en\/wp-json\/wp\/v2\/comments?post=7064"}],"version-history":[{"count":0,"href":"https:\/\/prochaska.eu\/en\/wp-json\/wp\/v2\/posts\/7064\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/prochaska.eu\/en\/wp-json\/wp\/v2\/media\/7070"}],"wp:attachment":[{"href":"https:\/\/prochaska.eu\/en\/wp-json\/wp\/v2\/media?parent=7064"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/prochaska.eu\/en\/wp-json\/wp\/v2\/categories?post=7064"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/prochaska.eu\/en\/wp-json\/wp\/v2\/tags?post=7064"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}